{"id":58,"date":"2015-02-09T16:09:03","date_gmt":"2015-02-09T16:09:03","guid":{"rendered":"http:\/\/www.cantokman.com\/?p=58"},"modified":"2015-02-09T16:10:46","modified_gmt":"2015-02-09T16:10:46","slug":"diseti-hastaliklari","status":"publish","type":"post","link":"https:\/\/www.cantokman.com\/fr\/maladies-des-gencives\/","title":{"rendered":"Maladies des gencives"},"content":{"rendered":"<p>Que veut-on dire quand on dit maladie des gencives : dent ; le tissu osseux qui l&#039;entoure; le tissu qui attache la dent \u00e0 l&#039;os (on l&#039;appelle le parodonte) et l&#039;os qui recouvre la dent\u00a0<strong>gencive<\/strong>\u00a0texture. Comme on peut le comprendre<strong>\u00a0<em>maladie des gencives<\/em><\/strong>\u00a0C&#039;est la maladie du syst\u00e8me.<\/p>\n<p>\u00c0 un moment donn\u00e9 de leur vie, 3 adultes sur 4 conna\u00eetront Pyor\u00e9e ou d<strong>maladie urinaire<\/strong>\u00a0Il est affect\u00e9 par la parodontite, \u00e9galement connue sous le nom de Les femmes, en particulier, sont \u00e0 risque de maladie parodontale \u00e0 certaines \u00e9tapes de leur vie. Les changements hormonaux peuvent affecter le flux sanguin vers les gencives et augmenter la r\u00e9ponse gingivale aux irritants de la plaque bact\u00e9rienne. Si vous pr\u00e9sentez un risque \u00e9lev\u00e9 de maladie parodontale, vous remarquerez que l&#039;\u00e9tat s&#039;aggrave \u00e0 ces moments-l\u00e0.<\/p>\n<p>CAUSE DES MALADIES GINGALES (parodontales) : Il s&#039;agit d&#039;une infection caus\u00e9e par une plaque bact\u00e9rienne collante attach\u00e9e \u00e0 la dent dans l&#039;os et la gencive autour de cette dent. Cette plaque bact\u00e9rienne produit des toxines (poisons) qui irritent vos gencives.<\/p>\n<p>maladie parodontale\u00a0<strong>gingivite<\/strong>\u00a0Dans les premi\u00e8res \u00e9tapes, appel\u00e9es gencives, les gencives gonflent, virent du rose au rouge et saignent facilement. La r\u00e9action du corps \u00e0 ces poisons (toxines) se pr\u00e9sente sous la forme d&#039;une s\u00e9paration des gencives des dents, et des cavit\u00e9s profondes appel\u00e9es poches gingivales se forment ici. Dans les derniers stades de la maladie parodontale, appel\u00e9e parodontite, l&#039;os et les tissus mous qui soutiennent la dent sont d\u00e9truits et la dent commence \u00e0 vaciller, auquel cas elle tombe d&#039;elle-m\u00eame ou doit \u00eatre extraite par un dentiste.<\/p>\n<p><strong>\u00c2ge de la pubert\u00e9 (adolescents)<\/strong><br \/>\nLorsque les filles atteignent la pubert\u00e9, la s\u00e9cr\u00e9tion des hormones sexuelles progest\u00e9rone et \u0153strog\u00e8ne augmente.Cet exc\u00e8s d&#039;hormones peut exacerber la r\u00e9ponse des gencives aux toxines de la plaque bact\u00e9rienne. Les gencives deviennent rouges, tendres, enfl\u00e9es et peuvent saigner facilement en mangeant ou en se brossant les dents.<\/p>\n<p><strong>P\u00e9riodes mensuelles<\/strong><br \/>\nPendant ces p\u00e9riodes, certaines femmes n&#039;observent pas de changement dans leurs tissus buccaux. Mais certaines peuvent avoir des gencives enfl\u00e9es, des plaies dans la bouche, du muguet, des glandes salivaires enfl\u00e9es ou des saignements des gencives, quelques jours avant le d\u00e9but des r\u00e8gles. Dans de tels cas, votre dentiste peut recommander des nettoyages sp\u00e9ciaux, des traitements des gencives et des anesth\u00e9siques topiques pour vous d\u00e9tendre.<\/p>\n<p><strong>Pilules contraceptives<\/strong><br \/>\nLe probl\u00e8me le plus courant chez les femmes qui utilisent ces pilules est la rougeur et le gonflement des gencives.Les hormones contenues dans les pilules contraceptives font augmenter le niveau de progest\u00e9rone dans votre syst\u00e8me. Dites \u00e0 votre dentiste que vous utilisez des pilules contraceptives. Ainsi, il peut trouver la bonne cause de l&#039;inconfort de vos gencives, ainsi que vous recommander des m\u00e9dicaments (comme des antibiotiques) qui peuvent att\u00e9nuer les effets secondaires de ces pilules.<\/p>\n<p><strong>Grossesse<\/strong><br \/>\nPendant la grossesse, les niveaux d&#039;hormones dans votre corps augmentent consid\u00e9rablement. La gingivite est particuli\u00e8rement fr\u00e9quente entre le 2e et le 8e mois de grossesse et peut provoquer des gencives rouges, enfl\u00e9es et douloureuses qui peuvent saigner lorsque vous vous brossez les dents. Cette sensibilit\u00e9 est une r\u00e9action extr\u00eame \u00e0 la plaque et est due \u00e0 une progest\u00e9rone excessivement \u00e9lev\u00e9e dans votre syst\u00e8me. Votre dentiste vous conseillera d&#039;\u00e9viter ces probl\u00e8mes durant le 2e trimestre et le premier trimestre de votre grossesse.\u00a0<strong>se brosser les dents plus souvent<\/strong>\u00a0peut vouloir.<\/p>\n<p><strong>M\u00e9nopause<\/strong><br \/>\nPendant la m\u00e9nopause, dans la bouche : sensation de br\u00fblure ; changements de go\u00fbt (sal\u00e9, poivr\u00e9, acide); Des changements physiques se produisent, tels qu&#039;une diminution du flux salivaire qui provoque une s\u00e9cheresse de la bouche et une hypersensibilit\u00e9 aux aliments ou aux boissons chauds\/froids. De nombreux m\u00e9dicaments peuvent avoir des effets secondaires dentaires qui peuvent \u00e9galement provoquer une s\u00e9cheresse de la bouche. Des m\u00e9dicaments stimulant la salive peuvent \u00eatre administr\u00e9s contre la bouche s\u00e8che.<\/p>\n<p><strong>LES MESURES<\/strong><\/p>\n<p><strong>M\u00e9thodes pour \u00e9viter les maladies parodontales :<\/strong><\/p>\n<ul>\n<li>Brossez-vous les dents deux fois par jour et nettoyez quotidiennement les surfaces interdentaires de vos dents avec du fil dentaire ou des nettoyants interdentaires.<\/li>\n<li>Si vous avez besoin de plus d&#039;aide pour pr\u00e9venir la plaque et la gingivite, votre dentiste peut vous recommander un rince-bouche antibiotique.<\/li>\n<li>Visitez votre dentiste r\u00e9guli\u00e8rement pour des examens et des pratiques de nettoyage professionnelles.<\/li>\n<li>Pour votre sant\u00e9, mangez \u00e9quilibr\u00e9 et limitez vos grignotages entre les repas.<\/li>\n<li><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Que veut-on dire quand on dit maladie des gencives : dent ; le tissu osseux qui l&#039;entoure; Le tissu qui attache la dent \u00e0 l&#039;os (que nous appelons le parodonte) et le tissu gingival qui recouvre l&#039;os entourant la dent. Comme on peut le comprendre, la maladie des gencives est la maladie de ce syst\u00e8me. \u00c0 un moment donn\u00e9 de leur vie, 3 adultes sur 4 seront touch\u00e9s par la parodontite, \u00e9galement connue sous le nom de pyorrh\u00e9e ou maladie des gencives. Les femmes, en particulier, peuvent d\u00e9velopper une maladie parodontale \u00e0 certains stades de leur [\u2026]<\/p>","protected":false},"author":2,"featured_media":59,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[14,6],"tags":[43,46,44,45,47,48],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/posts\/58"}],"collection":[{"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":0,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/posts\/58\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/media\/59"}],"wp:attachment":[{"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/media?parent=58"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/categories?post=58"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cantokman.com\/fr\/wp-json\/wp\/v2\/tags?post=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}